{"id":5252,"date":"2020-07-14T09:59:05","date_gmt":"2020-07-14T07:59:05","guid":{"rendered":"https:\/\/www.compagniadisanpaolo.it\/it\/?post_type=sdgs&#038;p=5252"},"modified":"2022-11-10T14:27:56","modified_gmt":"2022-11-10T13:27:56","slug":"sdg-13-lotta-contro-il-cambiamento-climatico","status":"publish","type":"sdgs","link":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/","title":{"rendered":"SDG 13  Lotta contro il cambiamento climatico"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row el_class=&#8221;txt-col mt-5 mb-3&#8243;][vc_column][vc_column_text]\n<h3 class=\"title\">Obiettivo 13: Promuovere azioni, a tutti i livelli, per combattere il cambiamento climatico.<\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;txt-col&#8221;][vc_column][vc_column_text el_class=&#8221;text&#8221;]\n<p class=\"p1\"><span class=\"s1\">Stiamo osservando, con sempre maggiore evidenza, gli <b>effetti del cambiamento climatico<\/b>, come <b>fenomeni meteorologici sempre pi\u00f9 estremi <\/b>e l\u2019<b>innalzamento del livello del mare<\/b>. Non si tratta di un percorso inevitabile, ma su cui possiamo agire riducendo le emissioni di gas a effetto serra derivanti da molte delle attivit\u00e0 umane. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Si tratta di una <b>sfida globale <\/b>ed \u00e8 quindi importante che <b>per questo Obiettivo di Sviluppo Sostenibile si impegnino tutte le Nazioni<\/b>, attivando politiche a favore delle <b>energie rinnovabili <\/b>e di un\u2019<b>economia a bassa emissione di carbonio<\/b>. <\/span><\/p>\n<p class=\"p1\"><span class=\"s1\">Contribuisce in modo prevalente al raggiungimento dell&#8217;SDG 13 (Sustainable Development Goal) l\u2019<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/le-nostre-sfide\/obiettivo-pianeta\/\">Obiettivo Pianeta<\/a> della Fondazione Compagnia di San Paolo. <\/span><\/p>\n<p><strong><a href=\"https:\/\/opendata.compagniadisanpaolo.it\/sdg\/13\" target=\"_blank\" rel=\"noopener\">Accedi al portale dei dati di contesto per conoscere il posizionamento di Piemonte, Liguria e Valle d\u2019Aosta rispetto all\u2019SDG 13<\/a><\/strong>.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;txt-col&#8221;][vc_column offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<div class=\"vc_row wpb_row vc_row-fluid mb-5 mt-3\">\n    \t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n    \t\t\t\t\t<div class=\"vc_column-inner\">\n    \t\n\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t<div class=\"vc_row wpb_row vc_inner vc_row-fluid\">\n\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper mb-5 mt-5\">\n\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\" style=\"text-align: center;\">Gli ultimi bandi, linee guida e scadenze uniche che contribuiscono al raggiungimento dell\u2019SDG 13<\/h3>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"bandi-related\">\n\t\t\t\t\t<div class=\"listing-box-wrap newsarchive\">\n\t\t\t\t\t\t<div class=\"listing-box obj-culture\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-culture\"><span>Cultura<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP_NEWS_Bando_internazionalizzazione-offerta-culturale_-815x350-1-540x310.png\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Bando per l\u2019internazionalizzazione dell\u2019offerta culturale\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\">\n\t\t\t\t    \t<span class=\"type\">CHIUSO<\/span>\n\t\t\t\t    \t<span class=\"date\">27\/02\/2026 - 21\/04\/2026<\/span>\n\t\t\t    \t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/contributi\/bando-per-linternazionalizzazione-dellofferta-culturale\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-planet\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-planet\"><span>Pianeta<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/simbiosi-head-540x310.jpg\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Simbiosi 2026 \u2013 Insieme alla natura per il futuro del Pianeta\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\">\n\t\t\t\t    \t<span class=\"type\">CHIUSO<\/span>\n\t\t\t\t    \t<span class=\"date\">15\/12\/2025 - 27\/02\/2026<\/span>\n\t\t\t    \t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/contributi\/simbiosi-2026-insieme-alla-natura-per-il-futuro-del-pianeta\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-people\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-people\"><span>Persone<\/span><\/span><span class=\"obj-planet\"><span>Pianeta<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP_bando_Verso_Politiche_locali_del_cibo_-815x350-1-540x310.png\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Verso politiche locali del cibo: sistemi territoriali e sostenibilit\u00e0 per  il contrasto alla povert\u00e0 alimentare\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\">\n\t\t\t\t    \t<span class=\"type\">CHIUSO<\/span>\n\t\t\t\t    \t<span class=\"date\">31\/07\/2025 - 07\/11\/2025<\/span>\n\t\t\t    \t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/contributi\/verso-politiche-locali-del-cibo-sistemi-territoriali-e-sostenibilita-per-il-contrasto-alla-poverta-alimentare\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div>\n\t\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-12 text-center\">\n\t\t\t  \t\t<a class=\"standard-link standard-link-fixed\" href=\"\/it\/cosa-facciamo\/contributi\/\">Tutti i contributi<\/a>\n\t\t\t\t<\/div>\n\t\t\t  <\/div>\t<\/div>\n\t        \t\t<\/div>\n\t        \t<\/div>\n\t\t\t<\/div>\n        <\/div>\n        \t\t\t\t<div style=\"clear:both\"><\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<div class=\"vc_row wpb_row vc_row-fluid mb-5 mt-3\">\n    \t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n    \t\t\t\t\t<div class=\"vc_column-inner\">\n    \t\n\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t<div class=\"vc_row wpb_row vc_inner vc_row-fluid\">\n\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper mb-5 mt-5\">\n\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\" style=\"text-align: center;\">Le ultime notizie che riguardano l'SDG 13<\/h3>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"bandi-related\">\n\t\t\t\t\t<div class=\"listing-box-wrap newsarchive\">\n\t\t\t\t\t\t<div class=\"listing-box obj-planet\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-planet\"><span>Pianeta<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/simbiosi-head-540x310.jpg\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Pubblicati gli esiti della Fase I del bando Simbiosi 2026\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\"><span class=\"type\">News<\/span><span class=\"date\">13 Maggio 2026<\/span>\n\t\t\t\t\t    \t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/news\/pubblicati-gli-esiti-della-fase-i-del-bando-simbiosi-2026\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-planet\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-planet\"><span>Pianeta<\/span><\/span><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/NEWS-Oasi-Pianeta_815X350-1-540x310.jpg\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Due anni di biodiversit\u00e0, innovazione e impatto misurabile per l&#8217;Oasi Pianeta\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\"><span class=\"type\">News<\/span><span class=\"date\">27 Marzo 2026<\/span>\n\t\t\t\t\t    \t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/news\/due-anni-di-biodiversita-innovazione-e-impatto-misurabile-per-loasi-pianeta\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-institutional\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP-placeholder-istituzionale-ambiente_815x350-540x310.jpg\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Foundations\u2019 actions for the EU Mission Climate-Neutral and Smart Cities 2026\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\"><span class=\"type\">News<\/span><span class=\"date\">20 Marzo 2026<\/span>\n\t\t\t\t\t    \t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/news\/foundations-actions-for-the-eu-mission-climate-neutral-and-smart-cities-2026\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-institutional\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP_NEWS_sostenibilita-approccio-integrato_-815x350-1-540x310.png\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Sostenibilit\u00e0: l\u2019approccio sistemico orientato all\u2019impatto della Fondazione\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\"><span class=\"type\">News<\/span><span class=\"date\">10 Marzo 2026<\/span>\n\t\t\t\t\t    \t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/news\/sostenibilita-lapproccio-sistemico-orientato-allimpatto-della-fondazione\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-culture\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-culture\"><span>Cultura<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP_NEWS_Bando_internazionalizzazione-offerta-culturale_-815x350-1-540x310.png\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Online il Bando per l\u2019internazionalizzazione dell\u2019offerta culturale del territorio.\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\"><span class=\"type\">News<\/span><span class=\"date\">27 Febbraio 2026<\/span>\n\t\t\t\t\t    \t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/news\/online-il-bando-per-linternazionalizzazione-dellofferta-culturale-del-territorio\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-institutional\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><span class=\"obj-culture\"><span>Cultura<\/span><\/span><span class=\"obj-people\"><span>Persone<\/span><\/span><span class=\"obj-planet\"><span>Pianeta<\/span><\/span><\/div><div class=\"image\">\n\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP_NEWS_-un-nuovo-capitolo-del-_Patto-con-il-territorio_DPA2026_-815x350-1-540x310.png\" class=\"attachment-full img-fluid wp-post-image\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            La Fondazione presenta il DPA 2026: un nuovo capitolo del &#8220;Patto con il territorio&#8221;\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\"><span class=\"type\">Eventi<\/span><span class=\"type\">News<\/span><span class=\"date\">20 Febbraio 2026<\/span>\n\t\t\t\t\t    \t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/news\/la-fondazione-presenta-il-dpa-2026-un-nuovo-capitolo-del-patto-con-il-territorio\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div>\n\t\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-12 text-center\">\n\t\t\t  <a class=\"standard-link standard-link-fixed\" href=\"\/news\">Tutte le news<\/a>\n\t\t\t\t<\/div>\n\t\t\t  <\/div>\t<\/div>\n\t        \t\t<\/div>\n\t        \t<\/div>\n\t\t\t<\/div>\n        <\/div>\n        \t\t\t\t<div style=\"clear:both\"><\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]<div class=\"vc_row wpb_row vc_row-fluid mb-5 mt-3\">\n    \t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n    \t\t\t\t\t<div class=\"vc_column-inner\">\n    \t\n\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t<div class=\"vc_row wpb_row vc_inner vc_row-fluid\">\n\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_text_column wpb_content_element \">\n\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper mb-5 mt-5\">\n\t\t\t\t\t\t\t\t\t\t<h3 class=\"title\" style=\"text-align: center;\">Gli ultimi comunicati stampa relativi all'SDG 13<\/h3>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"listing-grid listing-grid--small\">\n\t\t\t\t\t<div class=\"listing-box-wrap newsarchive\">Trovati 23 elementi\n\t\t\t\t\t\t<div class=\"listing-box obj-institutional\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><span class=\"obj-culture\"><span>Cultura<\/span><\/span><span class=\"obj-people\"><span>Persone<\/span><\/span><span class=\"obj-planet\"><span>Pianeta<\/span><\/span><\/div><div class=\"image\"><\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Un patto con il territorio: la fiducia come pilastro\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\">\n\t\t\t\t    \t<span class=\"type\">Comunicati<\/span>\n\t       \t  \t  \t\t<span class=\"date\">20 Febbraio 2026<\/span>\n\t\t\t    \t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/comunicati-stampa\/un-patto-con-il-territorio-la-fiducia-come-pilastro\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-institutional\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><\/div><div class=\"image\"><\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Torino si conferma hub internazionale per il deep tech: conclusa la VI edizione del programma di accelerazione Techstars\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\">\n\t\t\t\t    \t<span class=\"type\">Comunicati<\/span>\n\t       \t  \t  \t\t<span class=\"date\">23 Maggio 2025<\/span>\n\t\t\t    \t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/comunicati-stampa\/torino-si-conferma-hub-internazionale-per-il-deep-tech-conclusa-la-vi-edizione-del-programma-di-accelerazione-techstars\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-institutional\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><\/div><div class=\"image\"><\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            Comunicazione cessazione Patto Parasociale ai sensi dell\u2019art. 122 del Decreto Legislativo 24 febbraio 1998 n. 58 e dell\u2019art. 128 del regolamento  consob n. 11971\/99\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\">\n\t\t\t\t    \t<span class=\"type\">Comunicati<\/span>\n\t       \t  \t  \t\t<span class=\"date\">30 Aprile 2025<\/span>\n\t\t\t    \t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/comunicati-stampa\/comunicazione-cessazione-patto-parasociale-ai-sensi-dellart-122-del-decreto-legislativo-24-febbraio-1998-n-58-e-dellart-128-del-regolamento-consob-n-11971-99\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-institutional\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><\/div><div class=\"image\"><\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            La Fondazione Compagnia di San Paolo presenta a Genova il Piano Strategico 2025-2028\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\">\n\t\t\t\t    \t<span class=\"type\">Comunicati<\/span>\n\t       \t  \t  \t\t<span class=\"date\">15 Aprile 2025<\/span>\n\t\t\t    \t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/comunicati-stampa\/la-fondazione-compagnia-di-san-paolo-presenta-a-genova-il-piano-strategico-2025-2028\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<div class=\"listing-box obj-institutional\">\n\t\t\t\t\t\t\t<div class=\"vc_row wpb_row vc_row-fluid\">\n\t\t\t\t\t\t\t\t<div class=\"wpb_column vc_column_container vc_col-sm-12\">\n\t\t\t\t\t\t\t\t\t<div class=\"vc_column-inner\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"tag\"><span class=\"obj-institutional\"><span>Istituzionale<\/span><\/span><\/div><div class=\"image\"><\/div>\n\t\t\t\t<div class=\"text\">\n\t\t\t\t    <h4 class=\"title\">\n\t\t\t            La BCE autorizza il Patto di Preventiva Consultazione e Voto per l\u2019Assemblea di rinnovo del Consiglio di Amministrazione di Intesa Sanpaolo\n\t\t\t\t    <\/h4>\n\t\t\t\t    <div class=\"info\">\n\t\t\t\t    \t<span class=\"type\">Comunicati<\/span>\n\t       \t  \t  \t\t<span class=\"date\">20 Febbraio 2025<\/span>\n\t\t\t    \t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/comunicati-stampa\/la-bce-autorizza-il-patto-di-preventiva-consultazione-e-voto-per-lassemblea-di-rinnovo-del-consiglio-di-amministrazione-di-intesa-sanpaolo\/\" class=\"block-link\"><\/a>\n\t\t\t\t    <\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div><\/div>\n\t\t\t\t<div class=\"row\">\n\t\t\t\t<div class=\"col-12 text-center\">\n\t\t\t  \t<a class=\"standard-link standard-link-fixed\" href=\"\/it\/comunicati-stampa\/\">Tutti i comunicati stampa<\/a>\n\t\t\t\t<\/div>\n\t\t\t  <\/div>\t<\/div>\n\t        \t\t<\/div>\n\t        \t<\/div>\n\t\t\t<\/div>\n        <\/div>\n        \t\t\t\t<div style=\"clear:both\"><\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text el_class=&#8221;mb-0 mt-5&#8243;]\n<h3 style=\"text-align: center;\">Scopri il nostro impegno per gli Obiettivi di Sviluppo Sostenibile<\/h3>\n[\/vc_column_text][vc_column_text]<div class=\"sdg-list container d-none d-lg-block\">\n      \n      <div class=\"sdg-filter row\">\n\t<div class=\"col-4\">\n\t  <button data-filter=\"data-culture\" class=\"filter-button\">SDG<span style=\"text-transform: none;\">s<\/span> Obiettivo cultura<\/button>\n\t<\/div>\n\t<div class=\"col-4\">\n\t  <button data-filter=\"data-people\" class=\"filter-button\">SDG<span style=\"text-transform: none;\">s<\/span> Obiettivo persone<\/button>\n\t<\/div>\n\t<div class=\"col-4\">\n\t  <button data-filter=\"data-planet\" class=\"filter-button\">SDG<span style=\"text-transform: none;\">s<\/span> Obiettivo pianeta<\/button>\n\t<\/div>\n      <\/div>\n\n      <div class=\"sdg-wrap row\">\n\t<div class=\"sdg-box col-2\" data-people=\"1\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg01-it.svg\" class=\"img-fluid\" alt=\"Sconfiggere la povert\u00e0\">\n\t  <a href=\"\/it\/sdgs\/sdg-1-sconfiggere-la-poverta\/\" class=\"block-link\" title=\"Sconfiggere la povert\u00e0\"><\/a>\n\t<\/div>\n\t<div class=\"sdg-box col-2\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg02-it.svg\" class=\"img-fluid\" alt=\"Sconfiggere la fame\">\n\t  <a href=\"\/it\/sdgs\/sdg-2-sconfiggere-la-fame\/\" class=\"block-link\" title=\"Sconfiggere la fame\"><\/a>\n\t<\/div>    \n\t<div class=\"sdg-box col-2\" data-culture=\"1\" data-planet=\"1\" data-people=\"1\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg03-it.svg\" class=\"img-fluid\" alt=\"Salute e benessere\">\n\t  <a href=\"\/it\/sdgs\/sdg-3-salute-e-benessere\/\" class=\"block-link\" title=\"Salute e benessere\"><\/a>\n\t<\/div>\n\t<div class=\"sdg-box col-2\" data-culture=\"1\" data-people=\"1\" data-planet=\"1\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg04-it.svg\" class=\"img-fluid\" alt=\"Istruzione di qualit\u00e0\">\n\t  <a href=\"\/it\/sdgs\/sdg-4-istruzione-di-qualita\/\" class=\"block-link\" title=\"Istruzione di qualit\u00e0\"><\/a>\n\t<\/div>\n\t<div class=\"sdg-box col-2\" data-people=\"1\" data-culture=\"1\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg05-it.svg\" class=\"img-fluid\" alt=\"Parit\u00e0 di genere\">\n\t  <a href=\"\/it\/sdgs\/sdg-5-parita-di-genere\/\" class=\"block-link\" title=\"Parit\u00e0 di genere\"><\/a>\n\t<\/div>     \n\t<div class=\"sdg-box col-2\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg06-it.svg\" class=\"img-fluid\" alt=\"Acqua pulita e servizi igienico sanitari\">\n\t  <a href=\"\/it\/sdgs\/sdg-6-acqua-pulita-e-servizi-igienico-sanitari\/\" class=\"block-link\" title=\"Acqua pulita e servizi igienico sanitari\"><\/a>\n\t<\/div>\n\t<div class=\"sdg-box col-2\">\n\t  <img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg07-it.svg\" class=\"img-fluid\" alt=\"Energia pulita e accessibile\">\n\t<a href=\"\/it\/sdgs\/sdg-7-energia-pulita-e-accessibile\/\" class=\"block-link\" title=\"Energia pulita e accessibile\"><\/a>\n      <\/div>   \n      <div class=\"sdg-box col-2\" data-culture=\"1\" data-people=\"1\" data-planet=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg08-it.svg\" class=\"img-fluid\" alt=\"Lavoro dignitoso e crescita economica\">\n\t<a href=\"\/it\/sdgs\/sdg-8-lavoro-dignitoso-e-crescita-economica\/\" class=\"block-link\" title=\"Lavoro dignitoso e crescita economica\"><\/a>\n      <\/div>\n      <div class=\"sdg-box col-2\" data-culture=\"1\" data-planet=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg09-it.svg\" class=\"img-fluid\" alt=\"Imprese,innovazione e infrastrutture\">\n\t<a href=\"\/it\/sdgs\/sdg-9-imprese-innovazione-e-infrastrutture\/\" class=\"block-link\" title=\"Imprese,innovazione e infrastrutture\"><\/a>\n      <\/div>\n      <div class=\"sdg-box col-2\" data-culture=\"1\" data-people=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg10-it.svg\" class=\"img-fluid\" alt=\"Ridurre le disuguaglianze\">\n\t<a href=\"\/it\/sdgs\/sdg-10-ridurre-le-diseguaglianze\/\" class=\"block-link\" title=\"Ridurre le disuguaglianze\"><\/a>\n      <\/div>     \n      <div class=\"sdg-box col-2\" data-culture=\"1\" data-people=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg11-it.svg\" class=\"img-fluid\" alt=\"Citt\u00e0 e comunit\u00e0 sostenibili\">\n\t<a href=\"\/it\/sdgs\/sdg-11-citta-e-comunita-sostenibili\/\" class=\"block-link\" title=\"Citt\u00e0 e comunit\u00e0 sostenibili\"><\/a>\n      <\/div>\n      <div class=\"sdg-box col-2\" data-culture=\"1\" data-planet=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg12-it.svg\" class=\"img-fluid\" alt=\"Consumo e produzione responsabili\">\n\t<a href=\"\/it\/sdgs\/sdg-12-consumo-e-produzione-responsabili\/\" class=\"block-link\" title=\"Consumo e produzione responsabili\"><\/a>\n      <\/div>\n      <div class=\"sdg-box col-2\" data-planet=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg13-it.svg\" class=\"img-fluid\" alt=\"Lotta contro il cambiamento climatico\">\n\t<a href=\"\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/\" class=\"block-link\" title=\"Lotta contro il cambiamento climatico\"><\/a> \n      <\/div>\n      <div class=\"sdg-box col-2\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg14-it.svg\" class=\"img-fluid\" alt=\"Vita sott'acqua\">\n\t<a href=\"\/it\/sdgs\/sdg-14-vita-sottacqua\/\" class=\"block-link\" title=\"Vita sott'acqua\"><\/a> \n      <\/div>\n      <div class=\"sdg-box col-2\" data-planet=\"1\" data-culture=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg15-it.svg\" class=\"img-fluid\" alt=\"Vita sulla terra\">\n\t<a href=\"\/it\/sdgs\/sdg-15-vita-sulla-terra\/\" class=\"block-link\" title=\"Vita sulla terra\"><\/a> \n      <\/div>\n      <div class=\"sdg-box col-2\" data-culture=\"1\" data-planet=\"1\" data-people=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg16-it.svg\" class=\"img-fluid\" alt=\"Pace,giustizia e istituzioni solide\">\n\t<a href=\"\/it\/sdgs\/sdg-16-pace-giustizia-e-istituzioni-solide\/\" class=\"block-link\" title=\"Pace,giustizia e istituzioni solide\"><\/a>\n      <\/div>\n      <div class=\"sdg-box col-2\" data-culture=\"1\" data-people=\"1\" data-planet=\"1\">\n\t<img decoding=\"async\" src=\"\/wp-content\/uploads\/sdg17-it.svg\" class=\"img-fluid\" alt=\"Partnership per gli obiettivi\">\n\t<a href=\"\/it\/sdgs\/sdg-17-partnership-per-gli-obiettivi\/\" class=\"block-link\" title=\"Partnership per gli obiettivi\"><\/a>\n      <\/div>\n\n\n      <div class=\"sdg-cat col-2\">\n\t<a class=\"block-link\" title=\"\"><\/a>\n      <\/div>\n      \n    <\/div>   \n  <\/div>[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;txt-col&#8221;][vc_column offset=&#8221;vc_hidden-sm vc_hidden-xs&#8221;][vc_empty_space height=&#8221;40px&#8221;][\/vc_column][\/vc_row][vc_row full_width=&#8221;stretch_row_content&#8221; content_placement=&#8221;middle&#8221; el_class=&#8221;footer-sdg&#8221;][vc_column width=&#8221;5\/12&#8243; offset=&#8221;vc_col-sm-offset-1 vc_col-xs-offset-1 vc_col-xs-10&#8243;][vc_column_text]\n<h3 class=\"title\"><a href=\"https:\/\/unric.org\/it\/obiettivo-13-promuovere-azioni-a-tutti-i-livelli-per-combattere-il-cambiamento-climatico\/\" target=\"_blank\" rel=\"noopener noreferrer\">Approfondisci lo scenario e i traguardi, sul sito delle Nazioni Unite.<\/a><\/h3>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;1\/2&#8243; el_class=&#8221;img-right&#8221;][vc_single_image image=&#8221;5025&#8243; img_size=&#8221;full&#8221;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"featured_media":12174,"menu_order":25,"template":"","meta":{"_acf_changed":false,"content-type":""},"tags":[],"class_list":["post-5252","sdgs","type-sdgs","status-publish","has-post-thumbnail","hentry","entry","post-inner"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>SDG 13 Lotta contro il cambiamento climatico - Fondazione Compagnia di San Paolo<\/title>\n<meta name=\"description\" content=\"La lotta contro il cambiamento climatico \u00e8 una sfida globale che richiede l&#039;impegno di tutte le Nazioni nel ridurre le emissioni di gas a effetto serra - SDG 13\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SDG 13 Lotta contro il cambiamento climatico - Fondazione Compagnia di San Paolo\" \/>\n<meta property=\"og:description\" content=\"La lotta contro il cambiamento climatico \u00e8 una sfida globale che richiede l&#039;impegno di tutte le Nazioni nel ridurre le emissioni di gas a effetto serra - SDG 13\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Compagnia di San Paolo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CompagniaDiSanPaolo\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-10T13:27:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/alternate-social.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CSP_live\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/sdgs\\\/sdg-13-lotta-contro-il-cambiamento-climatico\\\/\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/sdgs\\\/sdg-13-lotta-contro-il-cambiamento-climatico\\\/\",\"name\":\"SDG 13 Lotta contro il cambiamento climatico - Fondazione Compagnia di San Paolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/sdgs\\\/sdg-13-lotta-contro-il-cambiamento-climatico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/sdgs\\\/sdg-13-lotta-contro-il-cambiamento-climatico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/HEADERS-SDGs-13_ITA.svg\",\"datePublished\":\"2020-07-14T07:59:05+00:00\",\"dateModified\":\"2022-11-10T13:27:56+00:00\",\"description\":\"La lotta contro il cambiamento climatico \u00e8 una sfida globale che richiede l'impegno di tutte le Nazioni nel ridurre le emissioni di gas a effetto serra - SDG 13\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/sdgs\\\/sdg-13-lotta-contro-il-cambiamento-climatico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/sdgs\\\/sdg-13-lotta-contro-il-cambiamento-climatico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/sdgs\\\/sdg-13-lotta-contro-il-cambiamento-climatico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/HEADERS-SDGs-13_ITA.svg\",\"contentUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/HEADERS-SDGs-13_ITA.svg\",\"width\":815,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/sdgs\\\/sdg-13-lotta-contro-il-cambiamento-climatico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SDG 13 Lotta contro il cambiamento climatico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\",\"name\":\"Fondazione Compagnia di San Paolo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#organization\",\"name\":\"Fondazione Compagnia di San Paolo\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/logo.svg\",\"width\":769,\"height\":323,\"caption\":\"Fondazione Compagnia di San Paolo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CompagniaDiSanPaolo\",\"https:\\\/\\\/x.com\\\/CSP_live\",\"http:\\\/\\\/instagram.com\\\/compagniadisanpaolo?ref=badge\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/compagnia-di-san-paolo\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/compagniadisanpaolo\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Compagnia_di_San_Paolo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SDG 13 Lotta contro il cambiamento climatico - Fondazione Compagnia di San Paolo","description":"La lotta contro il cambiamento climatico \u00e8 una sfida globale che richiede l'impegno di tutte le Nazioni nel ridurre le emissioni di gas a effetto serra - SDG 13","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/","og_locale":"it_IT","og_type":"article","og_title":"SDG 13 Lotta contro il cambiamento climatico - Fondazione Compagnia di San Paolo","og_description":"La lotta contro il cambiamento climatico \u00e8 una sfida globale che richiede l'impegno di tutte le Nazioni nel ridurre le emissioni di gas a effetto serra - SDG 13","og_url":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/","og_site_name":"Fondazione Compagnia di San Paolo","article_publisher":"https:\/\/www.facebook.com\/CompagniaDiSanPaolo","article_modified_time":"2022-11-10T13:27:56+00:00","og_image":[{"width":1200,"height":900,"url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/alternate-social.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@CSP_live","twitter_misc":{"Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/","url":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/","name":"SDG 13 Lotta contro il cambiamento climatico - Fondazione Compagnia di San Paolo","isPartOf":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/#primaryimage"},"image":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/HEADERS-SDGs-13_ITA.svg","datePublished":"2020-07-14T07:59:05+00:00","dateModified":"2022-11-10T13:27:56+00:00","description":"La lotta contro il cambiamento climatico \u00e8 una sfida globale che richiede l'impegno di tutte le Nazioni nel ridurre le emissioni di gas a effetto serra - SDG 13","breadcrumb":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/#primaryimage","url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/HEADERS-SDGs-13_ITA.svg","contentUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/HEADERS-SDGs-13_ITA.svg","width":815,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/sdgs\/sdg-13-lotta-contro-il-cambiamento-climatico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.compagniadisanpaolo.it\/it\/"},{"@type":"ListItem","position":2,"name":"SDG 13 Lotta contro il cambiamento climatico"}]},{"@type":"WebSite","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#website","url":"https:\/\/www.compagniadisanpaolo.it\/it\/","name":"Fondazione Compagnia di San Paolo","description":"","publisher":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.compagniadisanpaolo.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#organization","name":"Fondazione Compagnia di San Paolo","url":"https:\/\/www.compagniadisanpaolo.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/logo.svg","contentUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/logo.svg","width":769,"height":323,"caption":"Fondazione Compagnia di San Paolo"},"image":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CompagniaDiSanPaolo","https:\/\/x.com\/CSP_live","http:\/\/instagram.com\/compagniadisanpaolo?ref=badge","https:\/\/www.linkedin.com\/company\/compagnia-di-san-paolo","https:\/\/www.youtube.com\/user\/compagniadisanpaolo","https:\/\/it.wikipedia.org\/wiki\/Compagnia_di_San_Paolo"]}]}},"_links":{"self":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/sdgs\/5252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/sdgs"}],"about":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/types\/sdgs"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/media\/12174"}],"wp:attachment":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/media?parent=5252"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/tags?post=5252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}