{"id":11978,"date":"2021-03-02T10:51:22","date_gmt":"2021-03-02T09:51:22","guid":{"rendered":"https:\/\/www.compagniadisanpaolo.it\/?post_type=progetti&#038;p=11978"},"modified":"2024-09-27T11:51:49","modified_gmt":"2024-09-27T09:51:49","slug":"provaci-ancora-sam","status":"publish","type":"progetti","link":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/","title":{"rendered":"Provaci ancora Sam!"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_section][vc_row el_class=&#8221;txt-col mt-5 mb-3&#8243;][vc_column][vc_column_text]\n<h3 class=\"title\">Un progetto finalizzato a sperimentare nuovi modelli di didattica e migliorare i processi di apprendimento dei ragazzi, favorendo l&#8217;integrazione tra la realt\u00e0 scolastica e gli attori del territorio.<\/h3>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<div class=\"info-box mission\">\n\t\t<div class=\"info-box-wrap info-box-hor row pb-0\">\n\n\t\t      \n\t\t      <div class=\"spalla col-12 col-md-12\">\n\t\t\t<div class=\"info-box sharing-box\">\n\t\t\t  <span class=\"label\">Condividi:<\/span>\n\t\t\t  <div class=\"social-sharing\">\n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"fb\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/\" target=\"_blank\">\n\t\t\t\t<span class=\"sr-only\">Facebook<\/span>\n\t\t\t\t<i class=\"fab fa-facebook-f\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\t\t\t    \n\t\t\t    <style>\n.twitter, .twitter:hover{\ncolor:#000000 !important;}\n<\/style>\n\n\n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/\">\n\t\t\t\t<span class=\"sr-only\">Twitter<\/span>\n\t\t\t\t<i class=\"fa-brands fa-x-twitter\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\n\t\t\t    \n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/\">\n\t\t\t\t<span class=\"sr-only\">Linkedin<\/span>\n\t\t\t\t  <i class=\"fa-brands fa-linkedin-in\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"whatsapp\" href=\"whatsapp:\/\/send?text=https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/\" data-action=\"share\/whatsapp\/share\">\n\t\t\t\t<span class=\"sr-only\">Whatsapp<\/span>\n\t\t\t\t<i class=\"fa-brands fa-whatsapp\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"mail\" href=\"mailto:?subject=Provaci ancora Sam!&body=https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/\">\n\t\t\t\t<span class=\"sr-only\">Mail<\/span>\n\t\t\t\t <i class=\"fa-solid fa-envelope\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\t\t\t    \n\t\t\t  <\/div>\n\t\t\t<\/div>\n\t      <\/div>\n\t    <\/div><\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;page-content&#8221;][vc_column][vc_column_text el_class=&#8221;text&#8221;]\n<p class=\"p1\"><strong>Missione:<br \/>\n<a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/le-nostre-sfide\/obiettivo-persone\/educare-per-crescere-insieme\/\" target=\"_blank\" rel=\"noopener noreferrer\">Educare per crescere insieme<\/a><\/strong><\/p>\n<p>Il progetto <strong><a href=\"http:\/\/www.provaciancorasam.it\/\" target=\"_blank\" rel=\"noopener noreferrer\">Provaci ancora, Sam!<\/a><\/strong> ha come finalit\u00e0 generale quella di <strong>sperimentare nuovi modelli di didattica<\/strong>, con l\u2019obiettivo di garantire l\u2019acquisizione delle competenze irrinunciabili del primo ciclo di istruzione e l\u2019inclusione di tutte le alunne e tutti gli alunni del gruppo classe, <strong>favorendo l\u2019integrazione tra la realt\u00e0 scolastica e la realt\u00e0 extrascolastica<\/strong> e creando<strong> condizioni di dialogo costante tra la scuola e il territorio<\/strong> in cui si trova.<\/p>\n<p>A tale scopo, il progetto ricorre al tessuto connettivo delle associazioni senza scopo di lucro, agli oratori e alle parrocchie, avvalendosi delle potenzialit\u00e0 sociali ed educative delle stesse. <strong>Scuola e attori del territorio, in un lavoro congiunto, possono cos\u00ec favorire processi di apprendimento<\/strong> che, tenendo conto della storia di ciascuna ragazza e di ciascun ragazzo, diano a ognuno uno spazio di ascolto e di espressione di s\u00e9, offrendo luoghi e ambiti in cui poter rafforzare la propria autostima e trovare sostegno per il successo scolastico, nella logica pi\u00f9 generale del contrasto alla dispersione scolastica.<\/p>\n<p><strong>Gli obiettivi<\/strong> del progetto:<\/p>\n<ul>\n<li><strong>intervenire con un modello di intervento preventivo<\/strong> dalle classi 4\u00b0 e 5\u00b0 della Scuola Primaria fino alla Scuola Secondaria di primo grado, a partire dalla costruzione di un curricolo verticale e trasversale, fondato sul framework delle competenze, tra le quali quelle di cittadinanza;<\/li>\n<li><strong>Favorire il successo formativo di tutte le allieve e gli allievi<\/strong>, sperimentando nuove metodologie didattiche finalizzate all\u2019apprendimento e all\u2019inclusione;<\/li>\n<li><strong>Potenziare la sinergia con le risorse dell\u2019extra scuola e stimolare l\u2019inter-professionalit\u00e0<\/strong>, incoraggiando l\u2019integrazione tra il lavoro delle e dei docenti, quello delle operatrici educative e degli operatori educativi del contesto scuola e quello delle volontarie e dei volontari al fine di consolidare la \u201c<strong>comunit\u00e0 educante<\/strong>\u201d;<\/li>\n<li><strong>Diffondere l\u2019approccio del Provaci Ancora Sam anche alle classi non direttamente coinvolte nel Progetto<\/strong>, in un\u2019ottica di contaminazione, avvalendosi dell\u2019<strong>alleanza tra scuola e Organizzazioni territoriali<\/strong> come motore capace di proporre a studentesse e studenti un\u2019offerta ricca di potenziamento educativo e didattico fondato sull\u2019inclusione;<\/li>\n<li><strong>Reinserire le ragazze e i ragazzi<\/strong> che si sono allontanati dai circuiti formativi, nei percorsi scolastici e sociali, favorendo il <strong>conseguimento del titolo di studio<\/strong> conclusivo del primo ciclo di istruzione;<\/li>\n<li>Realizzare specifiche <strong>azioni di orientamento<\/strong> avvalendosi della collaborazione di Agenzie di formazione professionale, artigiani e Centro di Orientamento Scolastico e Professionale della Citt\u00e0 di Torino.<\/li>\n<\/ul>\n<p>Nel progetto sono coinvolti diversi partner, insieme alla Fondazione Compagnia di San Paolo: l&#8217;Ufficio Scolastico Regionale per Il Piemonte, la Citt\u00e0 di Torino, la Fondazione per la Scuola.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;sdg-list-wrap&#8221;][vc_column][vc_column_text el_class=&#8221;sdg-intro&#8221;]\n<h3 class=\"title\">Questo progetto contribuisce al raggiungimento dei seguenti Obiettivi di Sviluppo Sostenibile<\/h3>\n[\/vc_column_text][vc_raw_html]JTVCbW9zdHJhU0RHUyU1RA==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTVCU2V6aW9uZV9Eb2N1bWVudGklNUQ=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTVCZGlzZWduYV9jb3JyZWxhdGklNUQ=[\/vc_raw_html][\/vc_column][\/vc_row][\/vc_section]\n<\/div>","protected":false},"featured_media":11981,"menu_order":13,"template":"","meta":{"_acf_changed":false,"content-type":""},"tags":[51,81,70,95],"class_list":["post-11978","progetti","type-progetti","status-publish","has-post-thumbnail","hentry","tag-coesione-sociale","tag-comunita-educanti","tag-creazione-di-reti-solide","tag-mix-sociale","entry","post-inner"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Provaci ancora Sam! - Fondazione Compagnia di San Paolo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provaci ancora Sam! - Fondazione Compagnia di San Paolo\" \/>\n<meta property=\"og:description\" content=\"[vc_section][vc_row el_class=&#8221;txt-col mt-5 mb-3&#8243;][vc_column][vc_column_text] Un progetto finalizzato a sperimentare nuovi modelli di didattica e migliorare i processi di apprendimento dei ragazzi, favorendo l&#8217;integrazione tra la realt\u00e0 scolastica e gli attori del territorio. [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;page-content&#8221;][vc_column][vc_column_text el_class=&#8221;text&#8221;] Missione: Educare per crescere insieme Il progetto Provaci ancora, Sam! ha come finalit\u00e0 generale quella di sperimentare nuovi modelli di didattica, con l\u2019obiettivo di garantire l\u2019acquisizione delle competenze irrinunciabili del primo ciclo di istruzione e l\u2019inclusione di tutte le alunne e tutti gli alunni del gruppo classe, favorendo l\u2019integrazione tra la realt\u00e0 scolastica e la realt\u00e0 extrascolastica e creando condizioni di dialogo costante tra la scuola e il territorio in cui si trova. A tale scopo, il progetto ricorre al tessuto connettivo delle associazioni senza scopo di lucro, agli oratori e alle parrocchie, avvalendosi delle potenzialit\u00e0 sociali ed educative delle stesse. Scuola e attori del territorio, in un lavoro congiunto, possono cos\u00ec favorire processi di apprendimento che, tenendo conto della storia di ciascuna ragazza e di ciascun ragazzo, diano a ognuno uno spazio di ascolto e di espressione di s\u00e9, offrendo luoghi e ambiti in cui poter rafforzare la propria autostima e trovare sostegno per il successo scolastico, nella logica pi\u00f9 generale del contrasto alla dispersione scolastica. Gli obiettivi del progetto: intervenire con un modello di intervento preventivo dalle classi 4\u00b0 e 5\u00b0 della Scuola Primaria fino alla Scuola Secondaria di primo grado, a partire dalla costruzione di un curricolo verticale e trasversale, fondato sul framework delle competenze, tra le quali quelle di cittadinanza; Favorire il successo formativo di tutte le allieve e gli allievi, sperimentando nuove metodologie didattiche finalizzate all\u2019apprendimento e all\u2019inclusione; Potenziare la sinergia con le risorse dell\u2019extra scuola e stimolare l\u2019inter-professionalit\u00e0, incoraggiando l\u2019integrazione tra il lavoro delle e dei docenti, quello delle operatrici educative e degli operatori educativi del contesto scuola e quello delle volontarie e dei volontari al fine di consolidare la \u201ccomunit\u00e0 educante\u201d; Diffondere l\u2019approccio del Provaci Ancora Sam anche alle classi non direttamente coinvolte nel Progetto, in un\u2019ottica di contaminazione, avvalendosi dell\u2019alleanza tra scuola e Organizzazioni territoriali come motore capace di proporre a studentesse e studenti un\u2019offerta ricca di potenziamento educativo e didattico fondato sull\u2019inclusione; Reinserire le ragazze e i ragazzi che si sono allontanati dai circuiti formativi, nei percorsi scolastici e sociali, favorendo il conseguimento del titolo di studio conclusivo del primo ciclo di istruzione; Realizzare specifiche azioni di orientamento avvalendosi della collaborazione di Agenzie di formazione professionale, artigiani e Centro di Orientamento Scolastico e Professionale della Citt\u00e0 di Torino. Nel progetto sono coinvolti diversi partner, insieme alla Fondazione Compagnia di San Paolo: l&#8217;Ufficio Scolastico Regionale per Il Piemonte, la Citt\u00e0 di Torino, la Fondazione per la Scuola.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;sdg-list-wrap&#8221;][vc_column][vc_column_text el_class=&#8221;sdg-intro&#8221;] Questo progetto contribuisce al raggiungimento dei seguenti Obiettivi di Sviluppo Sostenibile [\/vc_column_text][vc_raw_html]JTVCbW9zdHJhU0RHUyU1RA==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTVCU2V6aW9uZV9Eb2N1bWVudGklNUQ=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTVCZGlzZWduYV9jb3JyZWxhdGklNUQ=[\/vc_raw_html][\/vc_column][\/vc_row][\/vc_section]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Compagnia di San Paolo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CompagniaDiSanPaolo\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-27T09:51:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/provaci-ancora-sam-header.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"815\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@CSP_live\" \/>\n<meta name=\"twitter:label1\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/progetti\\\/provaci-ancora-sam\\\/\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/progetti\\\/provaci-ancora-sam\\\/\",\"name\":\"Provaci ancora Sam! - Fondazione Compagnia di San Paolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/progetti\\\/provaci-ancora-sam\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/progetti\\\/provaci-ancora-sam\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/provaci-ancora-sam-header.jpg\",\"datePublished\":\"2021-03-02T09:51:22+00:00\",\"dateModified\":\"2024-09-27T09:51:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/progetti\\\/provaci-ancora-sam\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/progetti\\\/provaci-ancora-sam\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/progetti\\\/provaci-ancora-sam\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/provaci-ancora-sam-header.jpg\",\"contentUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/provaci-ancora-sam-header.jpg\",\"width\":815,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/progetti\\\/provaci-ancora-sam\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provaci ancora Sam!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\",\"name\":\"Fondazione Compagnia di San Paolo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#organization\",\"name\":\"Fondazione Compagnia di San Paolo\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/logo.svg\",\"width\":769,\"height\":323,\"caption\":\"Fondazione Compagnia di San Paolo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CompagniaDiSanPaolo\",\"https:\\\/\\\/x.com\\\/CSP_live\",\"http:\\\/\\\/instagram.com\\\/compagniadisanpaolo?ref=badge\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/compagnia-di-san-paolo\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/compagniadisanpaolo\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Compagnia_di_San_Paolo\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Provaci ancora Sam! - Fondazione Compagnia di San Paolo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/","og_locale":"it_IT","og_type":"article","og_title":"Provaci ancora Sam! - Fondazione Compagnia di San Paolo","og_description":"[vc_section][vc_row el_class=&#8221;txt-col mt-5 mb-3&#8243;][vc_column][vc_column_text] Un progetto finalizzato a sperimentare nuovi modelli di didattica e migliorare i processi di apprendimento dei ragazzi, favorendo l&#8217;integrazione tra la realt\u00e0 scolastica e gli attori del territorio. [\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text] [\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;page-content&#8221;][vc_column][vc_column_text el_class=&#8221;text&#8221;] Missione: Educare per crescere insieme Il progetto Provaci ancora, Sam! ha come finalit\u00e0 generale quella di sperimentare nuovi modelli di didattica, con l\u2019obiettivo di garantire l\u2019acquisizione delle competenze irrinunciabili del primo ciclo di istruzione e l\u2019inclusione di tutte le alunne e tutti gli alunni del gruppo classe, favorendo l\u2019integrazione tra la realt\u00e0 scolastica e la realt\u00e0 extrascolastica e creando condizioni di dialogo costante tra la scuola e il territorio in cui si trova. A tale scopo, il progetto ricorre al tessuto connettivo delle associazioni senza scopo di lucro, agli oratori e alle parrocchie, avvalendosi delle potenzialit\u00e0 sociali ed educative delle stesse. Scuola e attori del territorio, in un lavoro congiunto, possono cos\u00ec favorire processi di apprendimento che, tenendo conto della storia di ciascuna ragazza e di ciascun ragazzo, diano a ognuno uno spazio di ascolto e di espressione di s\u00e9, offrendo luoghi e ambiti in cui poter rafforzare la propria autostima e trovare sostegno per il successo scolastico, nella logica pi\u00f9 generale del contrasto alla dispersione scolastica. Gli obiettivi del progetto: intervenire con un modello di intervento preventivo dalle classi 4\u00b0 e 5\u00b0 della Scuola Primaria fino alla Scuola Secondaria di primo grado, a partire dalla costruzione di un curricolo verticale e trasversale, fondato sul framework delle competenze, tra le quali quelle di cittadinanza; Favorire il successo formativo di tutte le allieve e gli allievi, sperimentando nuove metodologie didattiche finalizzate all\u2019apprendimento e all\u2019inclusione; Potenziare la sinergia con le risorse dell\u2019extra scuola e stimolare l\u2019inter-professionalit\u00e0, incoraggiando l\u2019integrazione tra il lavoro delle e dei docenti, quello delle operatrici educative e degli operatori educativi del contesto scuola e quello delle volontarie e dei volontari al fine di consolidare la \u201ccomunit\u00e0 educante\u201d; Diffondere l\u2019approccio del Provaci Ancora Sam anche alle classi non direttamente coinvolte nel Progetto, in un\u2019ottica di contaminazione, avvalendosi dell\u2019alleanza tra scuola e Organizzazioni territoriali come motore capace di proporre a studentesse e studenti un\u2019offerta ricca di potenziamento educativo e didattico fondato sull\u2019inclusione; Reinserire le ragazze e i ragazzi che si sono allontanati dai circuiti formativi, nei percorsi scolastici e sociali, favorendo il conseguimento del titolo di studio conclusivo del primo ciclo di istruzione; Realizzare specifiche azioni di orientamento avvalendosi della collaborazione di Agenzie di formazione professionale, artigiani e Centro di Orientamento Scolastico e Professionale della Citt\u00e0 di Torino. Nel progetto sono coinvolti diversi partner, insieme alla Fondazione Compagnia di San Paolo: l&#8217;Ufficio Scolastico Regionale per Il Piemonte, la Citt\u00e0 di Torino, la Fondazione per la Scuola.[\/vc_column_text][\/vc_column][\/vc_row][vc_row el_class=&#8221;sdg-list-wrap&#8221;][vc_column][vc_column_text el_class=&#8221;sdg-intro&#8221;] Questo progetto contribuisce al raggiungimento dei seguenti Obiettivi di Sviluppo Sostenibile [\/vc_column_text][vc_raw_html]JTVCbW9zdHJhU0RHUyU1RA==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTVCU2V6aW9uZV9Eb2N1bWVudGklNUQ=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column][vc_raw_html]JTVCZGlzZWduYV9jb3JyZWxhdGklNUQ=[\/vc_raw_html][\/vc_column][\/vc_row][\/vc_section]","og_url":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/","og_site_name":"Fondazione Compagnia di San Paolo","article_publisher":"https:\/\/www.facebook.com\/CompagniaDiSanPaolo","article_modified_time":"2024-09-27T09:51:49+00:00","og_image":[{"width":815,"height":350,"url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/provaci-ancora-sam-header.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@CSP_live","twitter_misc":{"Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/","url":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/","name":"Provaci ancora Sam! - Fondazione Compagnia di San Paolo","isPartOf":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/#primaryimage"},"image":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/#primaryimage"},"thumbnailUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/provaci-ancora-sam-header.jpg","datePublished":"2021-03-02T09:51:22+00:00","dateModified":"2024-09-27T09:51:49+00:00","breadcrumb":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/#primaryimage","url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/provaci-ancora-sam-header.jpg","contentUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/provaci-ancora-sam-header.jpg","width":815,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/progetti\/provaci-ancora-sam\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.compagniadisanpaolo.it\/it\/"},{"@type":"ListItem","position":2,"name":"Provaci ancora Sam!"}]},{"@type":"WebSite","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#website","url":"https:\/\/www.compagniadisanpaolo.it\/it\/","name":"Fondazione Compagnia di San Paolo","description":"","publisher":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.compagniadisanpaolo.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#organization","name":"Fondazione Compagnia di San Paolo","url":"https:\/\/www.compagniadisanpaolo.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/logo.svg","contentUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/logo.svg","width":769,"height":323,"caption":"Fondazione Compagnia di San Paolo"},"image":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CompagniaDiSanPaolo","https:\/\/x.com\/CSP_live","http:\/\/instagram.com\/compagniadisanpaolo?ref=badge","https:\/\/www.linkedin.com\/company\/compagnia-di-san-paolo","https:\/\/www.youtube.com\/user\/compagniadisanpaolo","https:\/\/it.wikipedia.org\/wiki\/Compagnia_di_San_Paolo"]}]}},"_links":{"self":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/progetti\/11978","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/progetti"}],"about":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/types\/progetti"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/media\/11981"}],"wp:attachment":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/media?parent=11978"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/tags?post=11978"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}