{"id":37212,"date":"2025-05-06T12:28:31","date_gmt":"2025-05-06T10:28:31","guid":{"rendered":"https:\/\/www.compagniadisanpaolo.it\/?p=37212"},"modified":"2025-05-09T11:02:47","modified_gmt":"2025-05-09T09:02:47","slug":"inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte","status":"publish","type":"post","link":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/","title":{"rendered":"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_column_text css=&#8221;&#8221; el_class=&#8221;text-headline2&#8243;]Un percorso di riflessione collettiva sull\u2019identit\u00e0, la memoria e la rappresentazione attraverso l\u2019arte. Il Public Program #INSIDE propone una serie di appuntamenti con artisti, curatori e studiosi per esplorare nuovi immaginari e visioni pi\u00f9 inclusive del passato e del presente.[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column][vc_column_text]\n<div class=\"info-box mission\">\n\t\t<div class=\"info-box-wrap info-box-hor row pb-0\">\n\n\t\t      \n\t\t      <div class=\"spalla col-12 col-md-12\">\n\t\t\t<div class=\"info-box sharing-box\">\n\t\t\t  <span class=\"label\">Condividi:<\/span>\n\t\t\t  <div class=\"social-sharing\">\n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"fb\" href=\"https:\/\/www.facebook.com\/sharer.php?u=https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/\" target=\"_blank\">\n\t\t\t\t<span class=\"sr-only\">Facebook<\/span>\n\t\t\t\t<i class=\"fab fa-facebook-f\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\t\t\t    \n\t\t\t    <style>\n.twitter, .twitter:hover{\ncolor:#000000 !important;}\n<\/style>\n\n\n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"twitter\" href=\"https:\/\/twitter.com\/intent\/tweet?url=https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/\">\n\t\t\t\t<span class=\"sr-only\">Twitter<\/span>\n\t\t\t\t<i class=\"fa-brands fa-x-twitter\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\n\t\t\t    \n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"linkedin\" href=\"https:\/\/www.linkedin.com\/shareArticle?mini=true&url=https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/\">\n\t\t\t\t<span class=\"sr-only\">Linkedin<\/span>\n\t\t\t\t  <i class=\"fa-brands fa-linkedin-in\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"whatsapp\" href=\"whatsapp:\/\/send?text=https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/\" data-action=\"share\/whatsapp\/share\">\n\t\t\t\t<span class=\"sr-only\">Whatsapp<\/span>\n\t\t\t\t<i class=\"fa-brands fa-whatsapp\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\n\t\t\t    <span class=\"box\">\n\t\t\t      <a class=\"mail\" href=\"mailto:?subject=#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte&body=https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/\">\n\t\t\t\t<span class=\"sr-only\">Mail<\/span>\n\t\t\t\t <i class=\"fa-solid fa-envelope\"><\/i>\n\t\t\t      <\/a>\n\t\t\t    <\/span>\n\t\t\t    \n\t\t\t  <\/div>\n\t\t\t<\/div>\n\t      <\/div>\n\t    <\/div><\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row][vc_column width=&#8221;1\/4&#8243;][vc_column_text]\n\n\n\t\t<div class=\"info-box-wrap\">\n\n\t  <div class=\"info-box date-pub\">\n\t  \t<span class=\"label\">Data di pubblicazione:<\/span>\n\t    <span class=\"value\">6 Maggio 2025<\/span>\n\t  <\/div>\n\t\t\t\t  <div class=\"info-box obj-people\">\n\t\t\t\t\t  <div class=\"info-box obj\"><span class=\"label\">Obiettivo<\/span>\n\t\t\t\t\t    <div class=\"obj-small-box\">\n\t\t\t\t\t      <span>Persone.<\/span>\n\t\t\t\t\t    <\/div>\n\t\t\t\t\t  <\/div>\n\t\t\t\t  <\/div>\n\t\t\t  \n\t\t  \t   <div class=\"info-box obj-culture\">\n\t\t\t\t  <div class=\"info-box obj\"><span class=\"label\">Obiettivo<\/span>\n\t\t\t\t    <div class=\"obj-small-box\">\n\t\t\t\t      <span>Cultura.<\/span>\n\t\t\t\t    <\/div>\n\t\t\t\t  <\/div>\n\t\t\t  <\/div><div class=\"info-box mission\"><span class=\"label\">Tag<\/span><a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/tags\/risultati\/?_sft_post_tag=cultura-contemporanea\" class=\"tag-element\">Cultura contemporanea<\/a><a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/tags\/risultati\/?_sft_post_tag=gallerie-ditalia-torino\" class=\"tag-element\">Gallerie d'Italia Torino<\/a><a href=\"https:\/\/www.compagniadisanpaolo.it\/it\/tags\/risultati\/?_sft_post_tag=migrazioni\" class=\"tag-element\">Migrazioni<\/a><\/div>\t  \n\t<\/div>\n[\/vc_column_text][\/vc_column][vc_column width=&#8221;3\/4&#8243; el_class=&#8221;page-content&#8221;][vc_column_text css=&#8221;&#8221; el_class=&#8221;text&#8221;]Presso le <strong>Gallerie d\u2019Italia di Torino<\/strong> prosegue il <strong>Public Program #INSIDE<\/strong>, un ciclo di incontri curato dall\u2019<strong>Obiettivo Persone<\/strong> e dall\u2019<strong>Obiettivo Cultura<\/strong> della Fondazione Compagnia di San Paolo, in collaborazione con la<strong> Fondazione Circolo dei lettori<\/strong>, nati dal confronto con figure impegnate sui temi dell\u2019identit\u00e0, della rappresentazione, del linguaggio: <strong>Grace Fainelli<\/strong>, esperta di comunicazione inclusiva e linguaggi plurali; <strong>Hanane Makhloufi<\/strong>, poeta e curatrice del Black History Month Torino; <strong>Valentino Agunu<\/strong>, artista poliedrico: musicista, attore e performer.<\/p>\n<p>L\u2019iniziativa nasce con l\u2019intento di offrire uno spazio di riflessione e confronto su temi centrali per la comprensione del presente, tra cui il concetto di identit\u00e0, la rappresentazione, l\u2019evoluzione del linguaggio e la rilettura della storia attraverso le pratiche artistiche.<\/p>\n<p><strong>#INSIDE accoglie prospettive<\/strong> capaci di mettere in discussione le narrazioni dominanti, <strong>valorizzando approcci critici<\/strong> e visioni alternative.<\/p>\n<p>Particolare attenzione \u00e8 dedicata al <strong>tema dell\u2019afrodiscendenza<\/strong> e alla necessit\u00e0 di rileggere in chiave contemporanea l\u2019eredit\u00e0 coloniale e post-coloniale. Gli incontri vedono la partecipazione di artiste, artisti, curatrici, curatori, studiose e studiosi che, attraverso le loro ricerche e pratiche, propongono <strong>nuovi strumenti per abitare il presente<\/strong> in modo pi\u00f9 consapevole, inclusivo e giusto.<\/p>\n<p>Tra loro, <strong>Esp\u00e9rance Hakuzwimana<\/strong>, <strong>Nogaye Ndiaye<\/strong>, <strong>Daphne Di Cinto<\/strong>, <strong>Justin Randolph Thompson<\/strong>, <strong>Valerie Tameu<\/strong>, <strong>Wissal Houbabi<\/strong> e <strong>Sim\u00e3o Amista<\/strong>.<\/p>\n<p>Il ciclo si propone di mettere in luce il <strong>potenziale dell\u2019arte come forma di riparazione e trasformazione sociale<\/strong>: un mezzo per ricostruire la memoria, sanarne le fratture e restituirle voce, rendendo visibili esperienze e soggettivit\u00e0 spesso trascurate.<\/p>\n<p>Attraverso linguaggi visivi e performativi, <strong>#INSIDE intende attivare processi di cura individuale e collettiva<\/strong>, stimolare la partecipazione e contribuire alla costruzione di futuri pi\u00f9 equi e plurali.<\/p>\n<p>La partecipazione agli incontri \u00e8 gratuita, previa prenotazione sul sito delle <strong><a href=\"https:\/\/gallerieditalia.com\/it\/torino\/mostre-e-iniziative\/in-evidenza\/2025\/04\/17\/inside-torino-carrie-mae-weems-the-heart-of-the-matter\/\" target=\"_blank\" rel=\"noopener\">Gallerie d\u2019Italia<\/a><\/strong>.<\/p>\n<p>Di seguito si propone una panoramica completa delle mostre in programma:<\/p>\n<ul>\n<li><strong>Mercoledi\u0300 7 maggio 2025 h. 18.30 <\/strong><\/li>\n<\/ul>\n<p><strong>Parole, immagini, potere: un dialogo attorno alle parole che ci abitano <\/strong><\/p>\n<p>Dialogo con <strong>Espe\u0301rance Hakuzwimana <\/strong>e <strong>Nogaye Ndiaye <\/strong>modera <strong>Hanane Makhloufi <\/strong><\/p>\n<p>Un confronto sul linguaggio, le sue implicazioni e il suo potere di generare immaginari, tracciare confini, aprire possibilita\u0300. Il dialogo esplorera\u0300 come le parole contribuiscano a costruire rappresentazioni e visioni del mondo, influenzando il modo in cui ci riconosciamo, abitiamo il presente e immaginiamo futuri nuovi.<\/p>\n<p><strong>Espe\u0301rance Hakuzwimana <\/strong><em>scrittrice, ha pubblicato per Einaudi (Tutta intera, 2022 e Tra i bianchi di scuola, 2024) e Mondadori (La banda del pianerottolo, 2023). Dal 2022 e\u0300 consulente D&amp;I per Na.Co \u2013 Narrazioni Contaminate. <\/em><\/p>\n<p><strong>Nogaye Ndiaye <\/strong>dottoressa in giurisprudenza, scrittrice, formatrice e divulgatrice, impegnata nella sensibilizzazione online e offline su tematiche legate all\u2019antirazzismo, alla decolonizzazione e alla decostruzione degli stereotipi razzisti. E\u0300 autrice di <em>Fortunatamente nera: il risveglio di una mente colonizzata <\/em>e <em>Universo parallelo il paradigma del privilegio<\/em>.<\/p>\n<p><strong>Hanane Makhloufi <\/strong><em>scrittrice di poesia ed editor, coordinatrice e curatrice del Black History Month Torino e attivista per i diritti umani sul territorio torinese. Fondatrice di Sanduq Edicola Colletiva, un progetto di riqualificazione di un&#8217;ex edicola in San Salvario a Torino. <\/em><\/p>\n<ul>\n<li><strong>Giovedi\u0300 29 maggio 2025 h 18.00<br \/>\nRileggere la storia italiana: afrodiscendenze e memoria <\/strong>Dialogo con <strong>Daphne Di Cinto <\/strong>e <strong>Justin Randolph Thompson <\/strong>modera <strong>Valentino Agunu <\/strong><\/li>\n<\/ul>\n<p>La storia italiana e\u0300 attraversata da presenze afrodiscendenti che spesso restano invisibili nella memoria collettiva. L\u2019incontro propone una riflessione sulle storie rimosse, per restituire dignita\u0300 e visibilita\u0300 a chi ha contribuito a costruire l\u2019Italia di ieri e di oggi. Un dialogo che intreccia memoria, arti visive e narrazione, offrendo strumenti per ripensare l\u2019identita\u0300 collettiva e immaginare una rappresentazione storica piu\u0300 giusta e plurale.<\/p>\n<p><strong>Daphne Di Cinto <\/strong><em>attrice, sceneggiatrice, regista e attivista culturale, e\u0300 autrice de <\/em>Il Moro <em>(2021), cortometraggio sulla figura afrodiscendente di Alessandro de\u2019 Medici, che ha ottenuto riconoscimenti internazionali. Il suo lavoro ruota attorno alla rappresentazione delle identita\u0300 afroeuropee, alla rilettura decoloniale della storia e all\u2019empowerment attraverso l\u2019arte. Collabora con scuole, musei e istituzioni su temi legati a memoria, storia e rappresentazione. <\/em><\/p>\n<p><strong>Justin Randolph Thompson <\/strong>artista, educatore e facilitatore culturale statunitense, attivo tra Italia e USA dal 1999. E\u0300 co-fondatore e direttore dell&#8217;iniziativa Black History Month Florence e del centro di ricerca The Recovery Plan, entrambi dedicate alle culture afrodiscendenti in Italia. Il suo lavoro esplora le gerarchie sociali e istituzionali, intrecciando arte, attivismo e ricerca. Ha ricevuto numerosi riconoscimenti internazionali e ha esposto in musei come il Whitney Museum e il Museo MADRE.<\/p>\n<p><strong>Valentino Agunu<\/strong><em>, in arte WADO, e\u0300 un artista e musicista cosmopolita. Cresciuto tra Italia, Nigeria e Stati Uniti, WADO fonde Afrobeats, cultura italiana e influenze globali, dando voce a una generazione senza confini. Ex Hospital Corpsman della US Navy e attivista per i diritti dei figli di immigrati, ha portato la sua esperienza in musica, cinema e televisione. I suoi brani, prodotti tra Milano, New York e Lagos, raccontano storie di identita\u0300, appartenenza e orgoglio afro- italiano. <\/em><\/p>\n<ul>\n<li><strong>Mercoledi\u0300 11 giugno 2025, h 18.30<br \/>\nL\u2019arte come cura: memoria, trauma e trasformazione <\/strong>Dialogo con <strong>Valerie Tameu <\/strong>e <strong>Wissal Houbabi <\/strong>modera <strong>Sima\u0303o Amista.<\/strong><\/li>\n<\/ul>\n<p>Che ruolo puo\u0300 avere l\u2019arte nei processi di cura e di guarigione dai traumi coloniali e razziali? Un dialogo sull\u2019arte come pratica riparativa, capace di aprire nuovi immaginari, rendere visibile l\u2019invisibile e attivare processi di trasformazione sociale. Un incontro che si interroga sul potere del linguaggio artistico e performativo per rielaborare la memoria, ricucirne le ferite, riattivarne i sensi nascosti, restituirle voce.<\/p>\n<p><strong>Valerie Tameu <\/strong><em>artista e performer multidisciplinare. La sua pratica, ibrida ed esplorativa, unisce performance, tecnologia e pratiche decoloniali, indagando il rapporto tra memoria, immaginazione e corporeita\u0300. I suoi recenti lavori sono stati presentati in contesti come Ars Electronica, Centrale Fies, BASE Milano, Fondazione Sandretto Re Rebaudengo, e raccontati su L\u2019Espresso e Gucci Prospettive.<\/em><\/p>\n<p><strong>Wissal Houbabi <\/strong><em>poeta performativa, artista, scrittrice, direttrice artistica di Spore, hip hop head. Con la sua poesia scardina le convenzioni linguistiche e poetico, interrogando il rapporto tra lingue e dialetti, tra suono, stigma e senso. Nota per la sua radicalita\u0300 estetica e politica e capacita\u0300 di saper comunicare, ha lavorato con le principali istituzioni culturali, tra le quali Iuav, Goethe- Institut, Museo delle Civilta\u0300. Tra i suoi lavori: La Madelaine de Proust \u2013 La Vache qui Rit, pubblicato in Visible: Art as Policies for Care. Socially Engaged Art (2010\u2013Ongoing); Una gran puzza di merda nell\u2019aria, presentato al Milano Re-Mapped Summer Festival, al Compraverde 23 e alla XV Abba Cup; Attitudine. Anatomia di un occhio tagliato (Einaudi, 2023); Offesissima presso Ar\/ge Kunst Bolzano. <\/em><\/p>\n<p><strong>Sima\u0303o Amista <\/strong><em>docente e formatore, studioso di religioni e filosofie spirituali africane e afrodiscendenti. <\/em>[\/vc_column_text][vc_masonry_media_grid element_width=&#8221;6&#8243; css=&#8221;&#8221; grid_id=&#8221;vc_gid:1746781063754-f619ec26-d6e4-3&#8243; include=&#8221;37220,37218&#8243;][\/vc_column][\/vc_row][vc_row el_class=&#8221;sdg-list-wrap&#8221;][vc_column][vc_raw_html]JTVCbW9zdHJhU0RHUyU1RA==[\/vc_raw_html][\/vc_column][\/vc_row][vc_row el_class=&#8221;sdg-list-wrap&#8221;][vc_column][vc_raw_html]JTVCU2V6aW9uZV9Eb2N1bWVudGklNUQ=[\/vc_raw_html][\/vc_column][\/vc_row][vc_row][vc_column]<div class=\"templatera_shortcode\"><div data-vc-full-width=\"true\" data-vc-full-width-temp=\"true\" data-vc-full-width-init=\"false\" class=\"vc_row wpb_row vc_row-fluid newsletter-wrap\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_raw_code wpb_raw_html wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t    <div class=\"container\">\n      <div class=\"row align-items-center\">\n\t<div class=\"col-12 col-lg-6 col-xl-5 mb-3 mb-lg-0 pr-0\">\n\t  <h2 class=\"title\">Rimani aggiornato sui nostri bandi e sui nostri progetti<\/h2>\n\t<\/div>\n\t<div class=\"col-12 col-lg-6 col-xl-7 pl-xl-4\">\n\t  <a class=\"standard-link-block\" href=\"\/it\/newsletter\/\">\n\t    Compila il form e decidi su quale argomento vuoi ricevere notizie.\t    <strong>\u00a0 ISCRIVITI!<\/strong>\n\t  <\/a>\n\t<\/div>\n      <\/div>\n    <\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row-full-width vc_clearfix\"><\/div><\/div>[\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Un percorso di riflessione collettiva sull\u2019identit\u00e0, la memoria e la rappresentazione attraverso l\u2019arte. Il Public Program #Inside propone una serie di appuntamenti con artisti, curatori e studiosi per esplorare nuovi immaginari e visioni pi\u00f9 inclusive del passato e del presente.<\/p>\n","protected":false},"author":19,"featured_media":37230,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"content-type":"","footnotes":""},"categories":[17],"tags":[196,227,226],"class_list":["post-37212","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-cultura-contemporanea","tag-gallerie-ditalia-torino","tag-migrazioni","entry","post-inner"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte - Fondazione Compagnia di San Paolo<\/title>\n<meta name=\"description\" content=\"Un percorso di riflessione collettiva sull\u2019identit\u00e0, la memoria e la rappresentazione attraverso l\u2019arte.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte - Fondazione Compagnia di San Paolo\" \/>\n<meta property=\"og:description\" content=\"Un percorso di riflessione collettiva sull\u2019identit\u00e0, la memoria e la rappresentazione attraverso l\u2019arte.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/\" \/>\n<meta property=\"og:site_name\" content=\"Fondazione Compagnia di San Paolo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CompagniaDiSanPaolo\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T10:28:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-05-09T09:02:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png\" \/>\n\t<meta property=\"og:image:width\" content=\"815\" \/>\n\t<meta property=\"og:image:height\" content=\"350\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Federica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@CSP_live\" \/>\n<meta name=\"twitter:site\" content=\"@CSP_live\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Federica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/\"},\"author\":{\"name\":\"Federica\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#\\\/schema\\\/person\\\/b7d5451541c25c82f29c5be1e78456b2\"},\"headline\":\"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte\",\"datePublished\":\"2025-05-06T10:28:31+00:00\",\"dateModified\":\"2025-05-09T09:02:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/\"},\"wordCount\":1263,\"publisher\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png\",\"keywords\":[\"cultura contemporanea\",\"Gallerie d'Italia Torino\",\"migrazioni\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/\",\"name\":\"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte - Fondazione Compagnia di San Paolo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png\",\"datePublished\":\"2025-05-06T10:28:31+00:00\",\"dateModified\":\"2025-05-09T09:02:47+00:00\",\"description\":\"Un percorso di riflessione collettiva sull\u2019identit\u00e0, la memoria e la rappresentazione attraverso l\u2019arte.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png\",\"contentUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png\",\"width\":815,\"height\":350},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/news\\\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\",\"name\":\"Fondazione Compagnia di San Paolo\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#organization\",\"name\":\"Fondazione Compagnia di San Paolo\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/wp-content\\\/uploads\\\/logo.svg\",\"width\":769,\"height\":323,\"caption\":\"Fondazione Compagnia di San Paolo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/CompagniaDiSanPaolo\",\"https:\\\/\\\/x.com\\\/CSP_live\",\"http:\\\/\\\/instagram.com\\\/compagniadisanpaolo?ref=badge\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/compagnia-di-san-paolo\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/compagniadisanpaolo\",\"https:\\\/\\\/it.wikipedia.org\\\/wiki\\\/Compagnia_di_San_Paolo\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.compagniadisanpaolo.it\\\/it\\\/#\\\/schema\\\/person\\\/b7d5451541c25c82f29c5be1e78456b2\",\"name\":\"Federica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5698fa13ac389b1f1fb1263a4626e219d853d7ccf112e854aea8c9c087d24ae?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5698fa13ac389b1f1fb1263a4626e219d853d7ccf112e854aea8c9c087d24ae?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b5698fa13ac389b1f1fb1263a4626e219d853d7ccf112e854aea8c9c087d24ae?s=96&d=mm&r=g\",\"caption\":\"Federica\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte - Fondazione Compagnia di San Paolo","description":"Un percorso di riflessione collettiva sull\u2019identit\u00e0, la memoria e la rappresentazione attraverso l\u2019arte.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/","og_locale":"it_IT","og_type":"article","og_title":"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte - Fondazione Compagnia di San Paolo","og_description":"Un percorso di riflessione collettiva sull\u2019identit\u00e0, la memoria e la rappresentazione attraverso l\u2019arte.","og_url":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/","og_site_name":"Fondazione Compagnia di San Paolo","article_publisher":"https:\/\/www.facebook.com\/CompagniaDiSanPaolo","article_published_time":"2025-05-06T10:28:31+00:00","article_modified_time":"2025-05-09T09:02:47+00:00","og_image":[{"width":815,"height":350,"url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png","type":"image\/png"}],"author":"Federica","twitter_card":"summary_large_image","twitter_creator":"@CSP_live","twitter_site":"@CSP_live","twitter_misc":{"Scritto da":"Federica","Tempo di lettura stimato":"7 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/#article","isPartOf":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/"},"author":{"name":"Federica","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#\/schema\/person\/b7d5451541c25c82f29c5be1e78456b2"},"headline":"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte","datePublished":"2025-05-06T10:28:31+00:00","dateModified":"2025-05-09T09:02:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/"},"wordCount":1263,"publisher":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#organization"},"image":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png","keywords":["cultura contemporanea","Gallerie d'Italia Torino","migrazioni"],"articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/","url":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/","name":"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte - Fondazione Compagnia di San Paolo","isPartOf":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/#primaryimage"},"image":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/#primaryimage"},"thumbnailUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png","datePublished":"2025-05-06T10:28:31+00:00","dateModified":"2025-05-09T09:02:47+00:00","description":"Un percorso di riflessione collettiva sull\u2019identit\u00e0, la memoria e la rappresentazione attraverso l\u2019arte.","breadcrumb":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/#primaryimage","url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png","contentUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/CSP-Inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte_815X350.png","width":815,"height":350},{"@type":"BreadcrumbList","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/news\/inside-un-ciclo-di-incontri-per-rileggere-la-storia-attraverso-larte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.compagniadisanpaolo.it\/it\/"},{"@type":"ListItem","position":2,"name":"#INSIDE: un ciclo di incontri per rileggere la storia attraverso l\u2019arte"}]},{"@type":"WebSite","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#website","url":"https:\/\/www.compagniadisanpaolo.it\/it\/","name":"Fondazione Compagnia di San Paolo","description":"","publisher":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.compagniadisanpaolo.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#organization","name":"Fondazione Compagnia di San Paolo","url":"https:\/\/www.compagniadisanpaolo.it\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#\/schema\/logo\/image\/","url":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/logo.svg","contentUrl":"https:\/\/www.compagniadisanpaolo.it\/wp-content\/uploads\/logo.svg","width":769,"height":323,"caption":"Fondazione Compagnia di San Paolo"},"image":{"@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CompagniaDiSanPaolo","https:\/\/x.com\/CSP_live","http:\/\/instagram.com\/compagniadisanpaolo?ref=badge","https:\/\/www.linkedin.com\/company\/compagnia-di-san-paolo","https:\/\/www.youtube.com\/user\/compagniadisanpaolo","https:\/\/it.wikipedia.org\/wiki\/Compagnia_di_San_Paolo"]},{"@type":"Person","@id":"https:\/\/www.compagniadisanpaolo.it\/it\/#\/schema\/person\/b7d5451541c25c82f29c5be1e78456b2","name":"Federica","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/b5698fa13ac389b1f1fb1263a4626e219d853d7ccf112e854aea8c9c087d24ae?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b5698fa13ac389b1f1fb1263a4626e219d853d7ccf112e854aea8c9c087d24ae?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b5698fa13ac389b1f1fb1263a4626e219d853d7ccf112e854aea8c9c087d24ae?s=96&d=mm&r=g","caption":"Federica"}}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/posts\/37212","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/comments?post=37212"}],"version-history":[{"count":5,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/posts\/37212\/revisions"}],"predecessor-version":[{"id":37379,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/posts\/37212\/revisions\/37379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/media\/37230"}],"wp:attachment":[{"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/media?parent=37212"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/categories?post=37212"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.compagniadisanpaolo.it\/it\/wp-json\/wp\/v2\/tags?post=37212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}